{"id":67,"count":1,"description":"","link":"https:\/\/zinn.gr\/el\/tag\/travel\/","name":"Travel","slug":"travel","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Travel Archives - Z Inn Ioannina<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zinn.gr\/el\/tag\/travel\/\" \/>\n<meta property=\"og:locale\" content=\"el_GR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travel Archives - Z Inn Ioannina\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zinn.gr\/el\/tag\/travel\/\" \/>\n<meta property=\"og:site_name\" content=\"Z Inn Ioannina\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zinn.gr\/wp-content\/uploads\/2021\/08\/z_loading-e1628515912497.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zinn.gr\\\/tag\\\/travel\\\/\",\"url\":\"https:\\\/\\\/zinn.gr\\\/tag\\\/travel\\\/\",\"name\":\"Travel Archives - Z Inn Ioannina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zinn.gr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zinn.gr\\\/tag\\\/travel\\\/#breadcrumb\"},\"inLanguage\":\"el\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zinn.gr\\\/tag\\\/travel\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zinn.gr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zinn.gr\\\/#website\",\"url\":\"https:\\\/\\\/zinn.gr\\\/\",\"name\":\"Z Inn Ioannina\",\"description\":\"Z Inn Ioannina\",\"publisher\":{\"@id\":\"https:\\\/\\\/zinn.gr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zinn.gr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"el\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zinn.gr\\\/#organization\",\"name\":\"Z hotel Ioannina\",\"url\":\"https:\\\/\\\/zinn.gr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"el\",\"@id\":\"https:\\\/\\\/zinn.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zinn.gr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/z_loading-e1628515912497.gif\",\"contentUrl\":\"https:\\\/\\\/zinn.gr\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/z_loading-e1628515912497.gif\",\"width\":500,\"height\":500,\"caption\":\"Z hotel Ioannina\"},\"image\":{\"@id\":\"https:\\\/\\\/zinn.gr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/zhotelgr\",\"https:\\\/\\\/www.instagram.com\\\/zhotelgr\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Travel Archives - Z Inn Ioannina","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zinn.gr\/el\/tag\/travel\/","og_locale":"el_GR","og_type":"article","og_title":"Travel Archives - Z Inn Ioannina","og_url":"https:\/\/zinn.gr\/el\/tag\/travel\/","og_site_name":"Z Inn Ioannina","og_image":[{"width":500,"height":500,"url":"https:\/\/zinn.gr\/wp-content\/uploads\/2021\/08\/z_loading-e1628515912497.gif","type":"image\/gif"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zinn.gr\/tag\/travel\/","url":"https:\/\/zinn.gr\/tag\/travel\/","name":"Travel Archives - Z Inn Ioannina","isPartOf":{"@id":"https:\/\/zinn.gr\/#website"},"breadcrumb":{"@id":"https:\/\/zinn.gr\/tag\/travel\/#breadcrumb"},"inLanguage":"el"},{"@type":"BreadcrumbList","@id":"https:\/\/zinn.gr\/tag\/travel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zinn.gr\/"},{"@type":"ListItem","position":2,"name":"Travel"}]},{"@type":"WebSite","@id":"https:\/\/zinn.gr\/#website","url":"https:\/\/zinn.gr\/","name":"Z Inn Ioannina","description":"Z Inn Ioannina","publisher":{"@id":"https:\/\/zinn.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zinn.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"el"},{"@type":"Organization","@id":"https:\/\/zinn.gr\/#organization","name":"Z hotel Ioannina","url":"https:\/\/zinn.gr\/","logo":{"@type":"ImageObject","inLanguage":"el","@id":"https:\/\/zinn.gr\/#\/schema\/logo\/image\/","url":"https:\/\/zinn.gr\/wp-content\/uploads\/2021\/08\/z_loading-e1628515912497.gif","contentUrl":"https:\/\/zinn.gr\/wp-content\/uploads\/2021\/08\/z_loading-e1628515912497.gif","width":500,"height":500,"caption":"Z hotel Ioannina"},"image":{"@id":"https:\/\/zinn.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/zhotelgr","https:\/\/www.instagram.com\/zhotelgr\/"]}]}},"_links":{"self":[{"href":"https:\/\/zinn.gr\/el\/wp-json\/wp\/v2\/tags\/67","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zinn.gr\/el\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zinn.gr\/el\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zinn.gr\/el\/wp-json\/wp\/v2\/posts?tags=67"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}